{"id":2153,"date":"2023-11-22T07:10:05","date_gmt":"2023-11-22T15:10:05","guid":{"rendered":"https:\/\/www.attorneyoscar.com\/?p=2153"},"modified":"2024-10-01T20:37:51","modified_gmt":"2024-10-02T03:37:51","slug":"paso-a-paso-para-una-visa-de-trabajo-en-ee-uu","status":"publish","type":"post","link":"https:\/\/attorneyoscar.com\/es\/paso-a-paso-para-una-visa-de-trabajo-en-ee-uu\/","title":{"rendered":"PASO A PASO PARA UNA VISA DE TRABAJO EN EE.UU"},"content":{"rendered":"<h2><span style=\"color: #ff0000;\">Mira el video\u00a0<\/span> \u00a0<a href=\"https:\/\/fb.watch\/gmoMidCATm\">https:\/\/fb.watch\/gmoMidCATm<\/a><\/h2>\n<h2><span style=\"color: #ff0000;\">Pagina del gobierno ingresa\u00a0<\/span> \u00a0 <strong><a href=\"https:\/\/seasonaljobs.dol.gov\/es\">https:\/\/seasonaljobs.dol.gov\/es<\/a><\/strong><\/h2>\n<p>Trabajar con estatus legal en los Estados Unidos es el sue\u00f1o de muchas personas en<br \/>\nCentroamerica, hoy el abogado Oscar Ischiu te dar\u00e1 un paso a paso para que puedas<br \/>\ncumplir con este sue\u00f1o, recuerda seguir las instrucciones y no rendirte, a partir de hoy te<br \/>\nacompa\u00f1aremos para encontrar la oportunidad laboral que cambiara tu vida y la de tu<br \/>\nfamilia.<\/p>\n<h2><\/h2>\n<h2><span style=\"color: #ff0000;\">ESTE ES UN EJEMPLO PARA QUE PUEDA ENCONTRAR TRABAJO\u00a0<\/span><\/h2>\n<h2><span style=\"color: #0000ff;\"><strong>LEE TODOS LOS PASOS\u00a0<\/strong><\/span><\/h2>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-6352\" src=\"https:\/\/www.attorneyoscar.com\/wp-content\/uploads\/2023\/11\/a-214x300.jpg\" alt=\"\" width=\"214\" height=\"300\" srcset=\"https:\/\/attorneyoscar.com\/wp-content\/uploads\/2023\/11\/a-214x300.jpg 214w, https:\/\/attorneyoscar.com\/wp-content\/uploads\/2023\/11\/a-731x1024.jpg 731w, https:\/\/attorneyoscar.com\/wp-content\/uploads\/2023\/11\/a-768x1075.jpg 768w, https:\/\/attorneyoscar.com\/wp-content\/uploads\/2023\/11\/a.jpg 1080w\" sizes=\"auto, (max-width: 214px) 100vw, 214px\" \/><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-6353\" src=\"https:\/\/www.attorneyoscar.com\/wp-content\/uploads\/2023\/11\/b-214x300.jpg\" alt=\"\" width=\"214\" height=\"300\" srcset=\"https:\/\/attorneyoscar.com\/wp-content\/uploads\/2023\/11\/b-214x300.jpg 214w, https:\/\/attorneyoscar.com\/wp-content\/uploads\/2023\/11\/b-731x1024.jpg 731w, https:\/\/attorneyoscar.com\/wp-content\/uploads\/2023\/11\/b-768x1075.jpg 768w, https:\/\/attorneyoscar.com\/wp-content\/uploads\/2023\/11\/b.jpg 1080w\" sizes=\"auto, (max-width: 214px) 100vw, 214px\" \/><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-6354\" src=\"https:\/\/www.attorneyoscar.com\/wp-content\/uploads\/2023\/11\/d-214x300.jpg\" alt=\"\" width=\"214\" height=\"300\" srcset=\"https:\/\/attorneyoscar.com\/wp-content\/uploads\/2023\/11\/d-214x300.jpg 214w, https:\/\/attorneyoscar.com\/wp-content\/uploads\/2023\/11\/d-731x1024.jpg 731w, https:\/\/attorneyoscar.com\/wp-content\/uploads\/2023\/11\/d-768x1075.jpg 768w, https:\/\/attorneyoscar.com\/wp-content\/uploads\/2023\/11\/d.jpg 1080w\" sizes=\"auto, (max-width: 214px) 100vw, 214px\" \/><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-6355\" src=\"https:\/\/www.attorneyoscar.com\/wp-content\/uploads\/2023\/11\/c-214x300.jpg\" alt=\"\" width=\"214\" height=\"300\" srcset=\"https:\/\/attorneyoscar.com\/wp-content\/uploads\/2023\/11\/c-214x300.jpg 214w, https:\/\/attorneyoscar.com\/wp-content\/uploads\/2023\/11\/c-731x1024.jpg 731w, https:\/\/attorneyoscar.com\/wp-content\/uploads\/2023\/11\/c-768x1075.jpg 768w, https:\/\/attorneyoscar.com\/wp-content\/uploads\/2023\/11\/c.jpg 1080w\" sizes=\"auto, (max-width: 214px) 100vw, 214px\" \/><\/p>\n<h2><span style=\"color: #ff0000;\">SIGUE LOS PASOS<\/span><\/h2>\n<h2>PASO 1 CURRICULUM VITAE<\/h2>\n<p>Para obtener una visa de trabajo los requisitos varian seg\u00fan el tipo de habilidades,<br \/>\ntomando en cuenta esto debes crear un curr\u00edculum vitae muy atractivo, describe todas tus<br \/>\nhabilidades, experiencia, educaci\u00f3n y datos para ser contactado, es importante que tu CV<br \/>\nlo traduzcas al ingles esto puedes hacerlo en el traductor de google.<br \/>\nConsejo: cuida tu imagen en redes sociales.<\/p>\n<h2><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-1920\" src=\"https:\/\/www.attorneyoscar.com\/wp-content\/uploads\/2023\/11\/Imagen-de-WhatsApp-2023-11-03-a-las-12.14.44_b6fd2ca7-236x300.jpg\" alt=\"\" width=\"236\" height=\"300\" srcset=\"https:\/\/attorneyoscar.com\/wp-content\/uploads\/2023\/11\/Imagen-de-WhatsApp-2023-11-03-a-las-12.14.44_b6fd2ca7-236x300.jpg 236w, https:\/\/attorneyoscar.com\/wp-content\/uploads\/2023\/11\/Imagen-de-WhatsApp-2023-11-03-a-las-12.14.44_b6fd2ca7-804x1024.jpg 804w, https:\/\/attorneyoscar.com\/wp-content\/uploads\/2023\/11\/Imagen-de-WhatsApp-2023-11-03-a-las-12.14.44_b6fd2ca7-768x978.jpg 768w, https:\/\/attorneyoscar.com\/wp-content\/uploads\/2023\/11\/Imagen-de-WhatsApp-2023-11-03-a-las-12.14.44_b6fd2ca7-1207x1536.jpg 1207w, https:\/\/attorneyoscar.com\/wp-content\/uploads\/2023\/11\/Imagen-de-WhatsApp-2023-11-03-a-las-12.14.44_b6fd2ca7.jpg 1257w\" sizes=\"auto, (max-width: 236px) 100vw, 236px\" \/><br \/>\nPASO 2 CARTA DE PRESENTACI\u00d3N<\/h2>\n<p>Debes elaborar una carta de presentacion o de interes, consigna tus datos personales y los<br \/>\ndel remitente, es sumamente importante que la carta describa el tipo de oportunidad<br \/>\nlaboral que estas solicitando.<br \/>\nConsejo: no escribas m\u00e1s de dos p\u00e1rrafos. Menos texto es mejor.<\/p>\n<p>&nbsp;<\/p>\n<h2>PASO 3 CONTACTE EMPRESAS<\/h2>\n<p>Ingresa a la pagina del gobierno, atravez de este link\u00a0 \u00a0<strong>\u00a0<a href=\"https:\/\/seasonaljobs.dol.gov\/es\">https:\/\/seasonaljobs.dol.gov\/es<\/a>\u00a0<\/strong> y busca empresas que ofrezcan<br \/>\noportunidades de trabajo y envia tu CV y Carta de Presentacion puedas, insiste todos los<br \/>\ndias, envia cuantos correos puedas no importa si son 100 o 1,000 una puerta se abrira y<br \/>\nestar\u00e1s a 1 paso de cumplir tu sue\u00f1o de trabajar con estatus legal en los Estados Unidos.<br \/>\nConsejo: env\u00eda tantos correos electr\u00f3nicos como puedas, ponte metas diarias.<\/p>\n<p>&nbsp;<\/p>\n<h2>PASO 4 ENTREVISTA<\/h2>\n<p>Si has llegado a este paso felicidades, es muy probable que debas realizar una entrevista,<br \/>\npreparate para dar a conocer todas tus habilidades y dejar en claro porque te deben<br \/>\ncontratar, al finalizar la entrevista envia una carta agradeciendo el interes de la empresa<br \/>\nen contratarte.<br \/>\nConsejo: env\u00eda una carta de agradecimiento.<\/p>\n<p>Cumplidos estos pasos y cuando una empresa ofrezca una oferta de empleo firme, tu<br \/>\nfuturo empleador deber\u00e1 presentar el formulario I-129 al USCIS, con esto la empresa est\u00e1<\/p>\n<p>comunicando al gobierno estadounidense que solicita tus servicios y se inicia la solicitud<br \/>\nde visa de trabajo.<br \/>\nA partir de aqu\u00ed el empleador es qui\u00e9n realiza el tramite para tu visa de trabajo, si tienes<br \/>\nalguna duda o necesitas ayuda no dudes en contactar a nuestro equipo de expertos.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-1919\" src=\"https:\/\/www.attorneyoscar.com\/wp-content\/uploads\/2023\/11\/Imagen-de-WhatsApp-2023-11-03-a-las-12.14.44_ee8b1d03-300x200.jpg\" alt=\"\" width=\"300\" height=\"200\" srcset=\"https:\/\/attorneyoscar.com\/wp-content\/uploads\/2023\/11\/Imagen-de-WhatsApp-2023-11-03-a-las-12.14.44_ee8b1d03-300x200.jpg 300w, https:\/\/attorneyoscar.com\/wp-content\/uploads\/2023\/11\/Imagen-de-WhatsApp-2023-11-03-a-las-12.14.44_ee8b1d03-1024x684.jpg 1024w, https:\/\/attorneyoscar.com\/wp-content\/uploads\/2023\/11\/Imagen-de-WhatsApp-2023-11-03-a-las-12.14.44_ee8b1d03-768x513.jpg 768w, https:\/\/attorneyoscar.com\/wp-content\/uploads\/2023\/11\/Imagen-de-WhatsApp-2023-11-03-a-las-12.14.44_ee8b1d03.jpg 1280w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/p>\n<p>&nbsp;<\/p>\n\t\t\t<div class='shareThisWrapper'>\n\t\t\t\t<a target='_blank' class='dskSharingIcon dskSharingIcon_facebook' data-url='http:\/\/social.nextclient.com\/?site=fb&u=https%3A%2F%2Fattorneyoscar.com%2Fes%2Fpaso-a-paso-para-una-visa-de-trabajo-en-ee-uu%2F'><img loading=\"lazy\" decoding=\"async\" alt=\"Facebook\" title=\"Facebook\" src=\"https:\/\/d78c52a599aaa8c95ebc-9d8e71b4cb418bfe1b178f82d9996947.ssl.cf1.rackcdn.com\/dsk_sharing\/icons\/ftlg_16.png\" width=\"64\" height=\"16\"><\/a>\n\t\t\t\t<a target='_blank' class='dskSharingIcon dskSharingIcon_twitter' data-url='http:\/\/social.nextclient.com\/?site=tw&u=https%3A%2F%2Fattorneyoscar.com%2Fes%2Fpaso-a-paso-para-una-visa-de-trabajo-en-ee-uu%2F'><img loading=\"lazy\" decoding=\"async\" alt=\"Gorjeo\" title=\"Gorjeo\" src=\"https:\/\/d78c52a599aaa8c95ebc-9d8e71b4cb418bfe1b178f82d9996947.ssl.cf1.rackcdn.com\/dsk_sharing\/icons\/ftlg_16.png\" width=\"64\" height=\"16\"><\/a>\n\t\t\t\t<a target='_blank' class='dskSharingIcon dskSharingIcon_linkedin' data-url='http:\/\/social.nextclient.com\/?site=li&u=https%3A%2F%2Fattorneyoscar.com%2Fes%2Fpaso-a-paso-para-una-visa-de-trabajo-en-ee-uu%2F'><img loading=\"lazy\" decoding=\"async\" alt=\"LinkedIn\" title=\"LinkedIn\" src=\"https:\/\/d78c52a599aaa8c95ebc-9d8e71b4cb418bfe1b178f82d9996947.ssl.cf1.rackcdn.com\/dsk_sharing\/icons\/ftlg_16.png\" width=\"64\" height=\"16\"><\/a>\n\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Mira el video\u00a0 \u00a0https:\/\/fb.watch\/gmoMidCATm Pagina del gobierno ingresa\u00a0 \u00a0 https:\/\/seasonaljobs.dol.gov\/es Trabajar con estatus legal en los Estados Unidos es el sue\u00f1o de muchas personas en Centroamerica, hoy el abogado Oscar Ischiu te dar\u00e1 un paso a paso para que puedas cumplir con este sue\u00f1o, recuerda seguir las instrucciones y no rendirte, a partir de&#8230;  <a href=\"https:\/\/attorneyoscar.com\/es\/paso-a-paso-para-una-visa-de-trabajo-en-ee-uu\/\">Read More &raquo;<\/a><\/p>","protected":false},"author":3,"featured_media":6356,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[39],"tags":[],"class_list":["post-2153","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-spanish-on-english-domain-immigration"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/attorneyoscar.com\/es\/wp-json\/wp\/v2\/posts\/2153","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/attorneyoscar.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/attorneyoscar.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/attorneyoscar.com\/es\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/attorneyoscar.com\/es\/wp-json\/wp\/v2\/comments?post=2153"}],"version-history":[{"count":10,"href":"https:\/\/attorneyoscar.com\/es\/wp-json\/wp\/v2\/posts\/2153\/revisions"}],"predecessor-version":[{"id":6358,"href":"https:\/\/attorneyoscar.com\/es\/wp-json\/wp\/v2\/posts\/2153\/revisions\/6358"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/attorneyoscar.com\/es\/wp-json\/wp\/v2\/media\/6356"}],"wp:attachment":[{"href":"https:\/\/attorneyoscar.com\/es\/wp-json\/wp\/v2\/media?parent=2153"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/attorneyoscar.com\/es\/wp-json\/wp\/v2\/categories?post=2153"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/attorneyoscar.com\/es\/wp-json\/wp\/v2\/tags?post=2153"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}